{"id":2457990,"date":"2022-07-19T10:00:36","date_gmt":"2022-07-19T13:00:36","guid":{"rendered":"https:\/\/www.petz.com.br\/blog\/?p=2457990"},"modified":"2025-11-27T11:33:56","modified_gmt":"2025-11-27T14:33:56","slug":"domesticacao-de-animais","status":"publish","type":"post","link":"https:\/\/www.petz.com.br\/blog\/domesticacao-de-animais\/","title":{"rendered":"Como ocorreu a domestica\u00e7\u00e3o de animais? Descubra um pouco da hist\u00f3ria dos pets!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Voc\u00ea j\u00e1 olhou para o seu amiguinho de quatro patas e pensou: \u201cUau, estou vivendo com um animal em minha casa\u201d? Imaginar isso pode n\u00e3o ser t\u00e3o comum, mas quando refletimos sobre a <\/span><b>domestica\u00e7\u00e3o de animais<\/b><span style=\"font-weight: 400;\">, ter um cachorro, gato ou qualquer outro pet como seu companheiro di\u00e1rio fica muito mais interessante.<\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2457993 aligncenter\" src=\"https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-3.jpg\" alt=\"Gato em colo\" width=\"718\" height=\"482\" title=\"\" srcset=\"https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-3.jpg 718w, https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-3-300x201.jpg 300w, https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-3-150x101.jpg 150w\" sizes=\"(max-width: 718px) 100vw, 718px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Segundo dados do Instituto Pet Brasil, o Brasil ocupa a terceira posi\u00e7\u00e3o mundial em rela\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o de animais de estima\u00e7\u00e3o. S\u00e3o quase 140 milh\u00f5es de bichinhos, em sua maioria cachorros, aves e gatos. Mas como esses pets foram domesticados e se tornaram nossos amigos para a vida? Saiba mais a seguir!<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O que \u00e9 um animal domesticado?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Quando pensamos <\/span><b>no que \u00e9 a domestica\u00e7\u00e3o de animais<\/b><span style=\"font-weight: 400;\">, j\u00e1 nos v\u00eam \u00e0 cabe\u00e7a nossos pets, que convivem conosco diariamente. De fato, esses bichinhos t\u00eam uma longa hist\u00f3ria de domestica\u00e7\u00e3o e conviv\u00eancia com os humanos, mas n\u00e3o s\u00e3o apenas eles que s\u00e3o considerados animais dom\u00e9sticos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O <\/span><a href=\"https:\/\/www.petz.com.br\/blog\/comportamento\/curiosidades\/\"><span style=\"font-weight: 400;\">significado<\/span><\/a><span style=\"font-weight: 400;\"> de domestica\u00e7\u00e3o est\u00e1 diretamente relacionado ao condicionamento cont\u00ednuo de uma esp\u00e9cie \u00e0 conviv\u00eancia humana. Dessa maneira, existe uma s\u00e9rie de esp\u00e9cies animais e vegetais que passaram e ainda passam por esse processo, desde mil\u00eanios atr\u00e1s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Do latim, <\/span><i><span style=\"font-weight: 400;\">\u201cdomus\u201d <\/span><\/i><span style=\"font-weight: 400;\">significa \u201ccasa\u201d, enquanto <\/span><i><span style=\"font-weight: 400;\">\u201cdomesticus\u201d <\/span><\/i><span style=\"font-weight: 400;\">significa \u201ctrazer para a casa\u201d. N\u00e3o por coincid\u00eancia, a domestica\u00e7\u00e3o de animais come\u00e7ou no per\u00edodo Neol\u00edtico, quando os seres humanos deixaram de ser n\u00f4mades e passaram a fincar suas ra\u00edzes em lugares espec\u00edficos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">A partir da\u00ed, cerca de<\/span> <span style=\"font-weight: 400;\">20<\/span> <span style=\"font-weight: 400;\">mil anos atr\u00e1s, come\u00e7ou o processo de domestica\u00e7\u00e3o da fauna e da flora, come\u00e7ando por nossos amados cachorros. Naquela \u00e9poca, ainda eram lobos, que se aproveitavam das sobras das comidas dos humanos para se alimentar.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">A hist\u00f3ria da domestica\u00e7\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">N\u00e3o existe um ponto espec\u00edfico em que seres humanos decidiram que iriam come\u00e7ar a domestica\u00e7\u00e3o de animais. Esse foi um processo gradativo: a partir do momento em que nossas civiliza\u00e7\u00f5es passaram a nascer na \u00e1rea do Crescente F\u00e9rtil, entre os rios Tigre e Eufrates.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dessa maneira, pode-se dizer que a domestica\u00e7\u00e3o come\u00e7ou por uma quest\u00e3o log\u00edstica. Os lobos, por exemplo, buscavam as \u00e1reas habitadas por humanos atr\u00e1s de comida, enquanto humanos mantinham os lobos mais mansos por perto para ajudar em tarefas cotidianas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim, conforme os s\u00e9culos foram passando, esses lobos que eram especialmente escolhidos por humanos passaram a procriar, criando novas gera\u00e7\u00f5es com caracter\u00edsticas cada vez mais dom\u00e9sticas e menos selvagens. Assim, surgiram os cachorros e as <\/span><a href=\"https:\/\/www.petz.com.br\/blog\/raca-de-cachorro-mais-antiga-do-mundo\/\"><span style=\"font-weight: 400;\">diferentes ra\u00e7as<\/span><\/a><span style=\"font-weight: 400;\">, de acordo com diversas necessidades humanas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A domestica\u00e7\u00e3o de animais de produ\u00e7\u00e3o come\u00e7ou um pouco depois da dos lobos, h\u00e1 cerca de 10.000 anos, com cabras e ovelhas. Em seguida, vieram bois, porcos, burros, cavalos, etc. por todo o globo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mesmo com cada vez mais esp\u00e9cies se tornando <\/span><b>animais domesticados<\/b><span style=\"font-weight: 400;\">, algumas ainda estavam fora do alcance da humanidade. E continuam \u2014 a grande maioria dos animais n\u00e3o \u00e9 e nunca ser\u00e1 domesticada, e existe uma explica\u00e7\u00e3o para esse fato.<\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2457991 aligncenter\" src=\"https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais.jpg\" alt=\"Cachorro sendo domesticado\" width=\"718\" height=\"482\" title=\"\" srcset=\"https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais.jpg 718w, https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-300x201.jpg 300w, https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-150x101.jpg 150w\" sizes=\"(max-width: 718px) 100vw, 718px\" \/><\/p>\n<h2><span style=\"font-weight: 400;\">Quais esp\u00e9cies podem ser domesticadas<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Como h\u00e1 de se notar, mesmo mil\u00eanios depois de termos aprendido <\/span><b>como domesticar<\/b><span style=\"font-weight: 400;\"> animais, ainda h\u00e1 uma s\u00e9rie de animais selvagens. Esses animais, inclusive, s\u00e3o comumente proibidos por lei de serem domesticados. Por que n\u00e3o conseguimos ter todos esses bichinhos em casa?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Existem algumas regras a respeito de <\/span><b>quais animais podem ser domesticados<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">devem ser soci\u00e1veis;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">devem ter perdido o instinto selvagem ancestral;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">s\u00e3o capazes de se reproduzir em cativeiro;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">devem ter uma fun\u00e7\u00e3o especializada;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">precisam se adaptar a ambientes com facilidade.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Se uma esp\u00e9cie apresenta os cinco, pode ser considerada domesticada. \u00c9 importante pontuar aqui que um animal que apresenta apenas algumas dessas caracter\u00edsticas n\u00e3o \u00e9 dom\u00e9stico, e sim, na maioria das vezes, foi condicionado \u00e0quela situa\u00e7\u00e3o.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O impacto da domestica\u00e7\u00e3o<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">N\u00e3o \u00e9 pouco afirmar que o seu pet mudou a sua vida, n\u00e3o \u00e9 mesmo? O <\/span><b>impacto que a domestica\u00e7\u00e3o de animais teve na sa\u00fade humana<\/b><span style=\"font-weight: 400;\">, em nossos h\u00e1bitos e em nossas formas de conviv\u00eancia \u00e9 gigantesco. Tanto que hoje esses bichinhos s\u00e3o utilizados at\u00e9 para ajudar em tratamentos terap\u00eauticos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, a domestica\u00e7\u00e3o de animais (e plantas) tamb\u00e9m foi um grande alicerce para a constru\u00e7\u00e3o das civiliza\u00e7\u00f5es como conhecemos hoje. Nossas cidades puderam crescer com mais facilidade, ao mesmo tempo, domin\u00e2ncias pol\u00edticas e o avan\u00e7o de novas doen\u00e7as epid\u00eamicas tamb\u00e9m passaram a surgir.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O impacto n\u00e3o foi sentido s\u00f3 pelos humanos. Os animais tamb\u00e9m foram se transformando conforme a domestica\u00e7\u00e3o das esp\u00e9cies foi evoluindo. Estudos cient\u00edficos demonstram que algumas das mudan\u00e7as mais significativas que mam\u00edferos domesticados sofreram foram:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">colora\u00e7\u00e3o de pelagem mais variada;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">comportamento mais d\u00f3cil;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">diminui\u00e7\u00e3o do tamanho cerebral;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">matura\u00e7\u00e3o precoce;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">pedomorfose.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Assim, foram anos de hist\u00f3ria que uniram e transformaram tanto n\u00f3s, humanos, quanto os demais animais que fazem parte da nossa conviv\u00eancia. \u00c9 uma s\u00e9rie de comportamentos que criaram novas esp\u00e9cies que hoje s\u00e3o nossas melhores amigas.<\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2457992 aligncenter\" src=\"https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-2.jpg\" alt=\"Cachorro bebendo leite\" width=\"1024\" height=\"538\" title=\"\" srcset=\"https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-2.jpg 1024w, https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-2-300x158.jpg 300w, https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-2-768x404.jpg 768w, https:\/\/www.petz.com.br\/blog\/wp-content\/uploads\/2022\/07\/domesticacao-de-animais-2-150x79.jpg 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea gostou de conhecer um pouco mais sobre a hist\u00f3ria dos bichinhos que est\u00e3o sempre ao nosso lado, continue explorando os conte\u00fados que publicamos aqui, no blog da <\/span><a href=\"https:\/\/www.petz.com.br\/\"><span style=\"font-weight: 400;\">Petz<\/span><\/a><span style=\"font-weight: 400;\">! Falamos de curiosidades, cuidados e muito mais para voc\u00ea descobrir sobre nossos peludos!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea j\u00e1 olhou para o seu amiguinho de quatro patas e pensou: \u201cUau, estou vivendo [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":2457992,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[402,521],"tags":[],"class_list":["post-2457990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pets","category-curiosidades"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/posts\/2457990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2457990"}],"version-history":[{"count":0,"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/posts\/2457990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/media\/2457992"}],"wp:attachment":[{"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2457990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2457990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petz.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2457990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}